{"id":14941,"date":"2018-08-07T14:04:18","date_gmt":"2018-08-07T12:04:18","guid":{"rendered":"https:\/\/www.intolight.de\/?post_type=avada_portfolio&#038;p=14941"},"modified":"2020-12-01T19:41:15","modified_gmt":"2020-12-01T18:41:15","slug":"interactive-bicycle","status":"publish","type":"avada_portfolio","link":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/","title":{"rendered":"Interactive bicycle exhibit"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-bottom:60px;--awb-background-color:rgba(0,0,0,0);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><h1 style=\"text-align: center;\">Interactive bicycle<\/h1>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:11.52%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-padding-bottom:60px;--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.88%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-3 fusion-columns-total-3 fusion-content-boxes-1 content-boxes-icon-on-top content-left\" style=\"--awb-body-color:#ffffff;--awb-title-color:#ffffff;--awb-margin-top:10px;--awb-margin-bottom:20px;--awb-hover-accent-color:#333333;--awb-circle-hover-accent-color:#333333;\" data-animationOffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover content-box-column-first-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div class=\"icon\"><i style=\"border-color:#333333;border-width:1px;background-color:#333333;box-sizing:content-box;height:64px;width:64px;line-height:64px;border-radius:50%;font-size:32px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-handshake far circle-yes\"><\/i><\/div><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p style=\"text-align: center;\"><strong>Client<br \/>\n<\/strong><a href=\"https:\/\/plus.aok.de\/\">AOK<\/a><\/p>\n<p style=\"text-align: center;\"><strong>Partner<br \/>\n<\/strong><a href=\"https:\/\/www.queo.de\/\">Queo<\/a><\/p>\n<\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover \"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div class=\"icon\"><i style=\"border-color:#333333;border-width:1px;background-color:#333333;box-sizing:content-box;height:64px;width:64px;line-height:64px;border-radius:50%;font-size:32px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-calendar far circle-yes\"><\/i><\/div><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p style=\"text-align: center;\"><strong>Task<br \/>\n<\/strong>Development of an interactive bicycle<\/p>\n<\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);\" class=\"fusion-column content-box-column content-box-column content-box-column-3 col-lg-4 col-md-4 col-sm-4 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon icon-hover-animation-fade\" data-animationOffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div class=\"icon\"><i style=\"border-color:#333333;border-width:1px;background-color:#333333;box-sizing:content-box;height:64px;width:64px;line-height:64px;border-radius:50%;font-size:32px;\" aria-hidden=\"true\" class=\"fontawesome-icon fa-tags fas circle-yes\"><\/i><\/div><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">\n<p style=\"text-align: center;\"><strong>Categories<br \/>\n<\/strong>[php_everywhere]\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#444444;border-top-width:1px;\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:11.52%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:11.52%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:2.88%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p>During the &#8220;Dein Herz und Du&#8221; campaign, the AOK Sachsen-Anhalt organized a tour under the hashtag #herzhelfer in June 2018.<br \/>\nTogether with the agency Queo we developed an interactive bicycle. At events in four different cities, visitors could train with it and collect kilometers together. These were paid out after the tour in the form of donations to the German Heart Foundation.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_6 1_6 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:16.666666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:11.52%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:11.52%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\" style=\"border:2px solid rgba(0,0,0,0);\"><a href=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[gallery01]\" data-caption=\"interaktives Fahrrad\" data-title=\"interaktives Fahrrad\" title=\"interaktives Fahrrad\"><img decoding=\"async\" width=\"1520\" height=\"1100\" src=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px.jpg\" alt class=\"img-responsive wp-image-15069\" srcset=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px-200x145.jpg 200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px-400x289.jpg 400w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px-600x434.jpg 600w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px-800x579.jpg 800w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px-1200x868.jpg 1200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0002_180613_AOK-SAN_Herz2018_Magdeburg_Radeln_5_fb-1200x800px.jpg 1520w\" sizes=\"(max-width: 800px) 100vw, 1200px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:40px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_6 1_6 fusion-one-sixth fusion-column-first\" style=\"--awb-bg-size:cover;width:16.666666666667%;width:calc(16.666666666667% - ( ( 4% + 4% ) * 0.16666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_2_3 2_3 fusion-two-third\" style=\"--awb-bg-size:cover;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% + 4% ) * 0.66666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-3\"><h2 style=\"text-align: center;\">The interactive bike<\/h2>\n<p>We have equipped a standard home trainer with different sensors A 55-inch display &#8211; linked to the virtual route &#8211; visualizes the growth of a balloon. Meanwhile, the balloon pulses to the beat of the rider&#8217;s heartbeat. The direct visual feedback provides a captivating, sporty experience.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_6 1_6 fusion-one-sixth fusion-column-last\" style=\"--awb-bg-size:cover;width:16.666666666667%;width:calc(16.666666666667% - ( ( 4% + 4% ) * 0.16666666666667 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\" style=\"border:2px solid rgba(0,0,0,0);\"><a href=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[gallery01]\" data-caption=\"interaktives Fahrrad\" data-title=\"interaktives Fahrrad\" title=\"interaktives Fahrrad\"><img decoding=\"async\" width=\"1520\" height=\"1100\" src=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095.jpg\" alt class=\"img-responsive wp-image-15073\" srcset=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095-200x145.jpg 200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095-400x289.jpg 400w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095-600x434.jpg 600w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095-800x579.jpg 800w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095-1200x868.jpg 1200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0004_DSC08095.jpg 1520w\" sizes=\"(max-width: 800px) 100vw, 1200px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-first\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-none\" style=\"border:2px solid rgba(0,0,0,0);\"><a href=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[gallery01]\" data-caption=\"interaktives Fahrrad\" data-title=\"interaktives Fahrrad\" title=\"interaktives Fahrrad\"><img decoding=\"async\" width=\"1520\" height=\"1100\" src=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148.jpg\" alt class=\"img-responsive wp-image-15070\" srcset=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148-200x145.jpg 200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148-400x289.jpg 400w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148-600x434.jpg 600w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148-800x579.jpg 800w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148-1200x868.jpg 1200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0001_DSC08148.jpg 1520w\" sizes=\"(max-width: 800px) 100vw, 400px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_3 1_3 fusion-one-third\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-none\" style=\"border:2px solid rgba(0,0,0,0);\"><a href=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[gallery01]\" data-caption=\"interaktives Fahrrad\" data-title=\"interaktives Fahrrad\" title=\"interaktives Fahrrad\"><img decoding=\"async\" width=\"1520\" height=\"1100\" src=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086.jpg\" alt class=\"img-responsive wp-image-15071\" srcset=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086-200x145.jpg 200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086-400x289.jpg 400w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086-600x434.jpg 600w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086-800x579.jpg 800w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086-1200x868.jpg 1200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0006_DSC08086.jpg 1520w\" sizes=\"(max-width: 800px) 100vw, 400px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-none\" style=\"border:2px solid rgba(0,0,0,0);\"><a href=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[gallery01]\" data-caption=\"interaktives Fahrrad\" data-title=\"interaktives Fahrrad\" title=\"interaktives Fahrrad\"><img decoding=\"async\" width=\"1520\" height=\"1100\" src=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093.jpg\" alt class=\"img-responsive wp-image-15072\" srcset=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093-200x145.jpg 200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093-400x289.jpg 400w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093-600x434.jpg 600w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093-800x579.jpg 800w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093-1200x868.jpg 1200w, https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/1520-x-1100_0005_DSC08093.jpg 1520w\" sizes=\"(max-width: 800px) 100vw, 400px\" \/><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:40px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_6 1_6 fusion-one-sixth fusion-column-first\" style=\"--awb-bg-size:cover;width:16.666666666667%;width:calc(16.666666666667% - ( ( 4% + 4% ) * 0.16666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_2_3 2_3 fusion-two-third\" style=\"--awb-bg-size:cover;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% + 4% ) * 0.66666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-4\"><h2 style=\"text-align: center;\">Innovative technology<\/h2>\n<p class=\"p1\"><span class=\"Apple-converted-space\">For example, we used an infrared sensor to track the speed of the bicycle. We used a 3D printer to produce mounts for cables and microelectronics. On the software side, we use \u00a0<\/span><a href=\"https:\/\/vvvv.org\/\">VVVV<\/a> to evaluate the recorded data and transfer it into suitable animations.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_6 1_6 fusion-one-sixth fusion-column-last\" style=\"--awb-bg-size:cover;width:16.666666666667%;width:calc(16.666666666667% - ( ( 4% + 4% ) * 0.16666666666667 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":14958,"menu_order":26,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"portfolio_category":[62,75],"portfolio_skills":[66,68,70],"portfolio_tags":[],"class_list":["post-14941","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-interactive-exhibits","portfolio_category-trade-fair","portfolio_skills-data-visualization","portfolio_skills-game-design","portfolio_skills-ui-design-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>An interactive bicycle exhibit with different sensors for events or trade fairs<\/title>\n<meta name=\"description\" content=\"We have equipped a standard home trainer with various sensors and transformed it into an innovativ interactive bicycle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"An interactive bicycle exhibit with different sensors for events or trade fairs\" \/>\n<meta property=\"og:description\" content=\"We have equipped a standard home trainer with various sensors and transformed it into an innovativ interactive bicycle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/\" \/>\n<meta property=\"og:site_name\" content=\"Intolight\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/intolight.de\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-01T18:41:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/titelbild-1520px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1520\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/\",\"url\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/\",\"name\":\"An interactive bicycle exhibit with different sensors for events or trade fairs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.intolight.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.intolight.de\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/titelbild-1520px.jpg\",\"datePublished\":\"2018-08-07T12:04:18+00:00\",\"dateModified\":\"2020-12-01T18:41:15+00:00\",\"description\":\"We have equipped a standard home trainer with various sensors and transformed it into an innovativ interactive bicycle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.intolight.de\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/titelbild-1520px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.intolight.de\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/titelbild-1520px.jpg\",\"width\":1520,\"height\":1100,\"caption\":\"interaktives Fahrrad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/interactive-bicycle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/www.intolight.de\\\/en\\\/portfolio-items\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Interactive bicycle exhibit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.intolight.de\\\/#website\",\"url\":\"https:\\\/\\\/www.intolight.de\\\/\",\"name\":\"Intolight\",\"description\":\"digital. experience. design.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.intolight.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.intolight.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.intolight.de\\\/#organization\",\"name\":\"intolight\",\"url\":\"https:\\\/\\\/www.intolight.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.intolight.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.intolight.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/1520-x-1100_0004_Dave_Kreuzkirche_2016-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.intolight.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/1520-x-1100_0004_Dave_Kreuzkirche_2016-2.jpg\",\"width\":1520,\"height\":1100,\"caption\":\"intolight\"},\"image\":{\"@id\":\"https:\\\/\\\/www.intolight.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/intolight.de\",\"https:\\\/\\\/x.com\\\/intolightfeed\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/intolight\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCG6VNyutvmFQ6NuEwAmZxeg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"An interactive bicycle exhibit with different sensors for events or trade fairs","description":"We have equipped a standard home trainer with various sensors and transformed it into an innovativ interactive bicycle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/","og_locale":"en_US","og_type":"article","og_title":"An interactive bicycle exhibit with different sensors for events or trade fairs","og_description":"We have equipped a standard home trainer with various sensors and transformed it into an innovativ interactive bicycle.","og_url":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/","og_site_name":"Intolight","article_publisher":"https:\/\/www.facebook.com\/intolight.de","article_modified_time":"2020-12-01T18:41:15+00:00","og_image":[{"width":1520,"height":1100,"url":"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/titelbild-1520px.jpg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/","url":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/","name":"An interactive bicycle exhibit with different sensors for events or trade fairs","isPartOf":{"@id":"https:\/\/www.intolight.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/#primaryimage"},"image":{"@id":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/titelbild-1520px.jpg","datePublished":"2018-08-07T12:04:18+00:00","dateModified":"2020-12-01T18:41:15+00:00","description":"We have equipped a standard home trainer with various sensors and transformed it into an innovativ interactive bicycle.","breadcrumb":{"@id":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/#primaryimage","url":"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/titelbild-1520px.jpg","contentUrl":"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/08\/titelbild-1520px.jpg","width":1520,"height":1100,"caption":"interaktives Fahrrad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intolight.de\/en\/portfolio-items\/interactive-bicycle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intolight.de\/en\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/www.intolight.de\/en\/portfolio-items\/"},{"@type":"ListItem","position":3,"name":"Interactive bicycle exhibit"}]},{"@type":"WebSite","@id":"https:\/\/www.intolight.de\/#website","url":"https:\/\/www.intolight.de\/","name":"Intolight","description":"digital. experience. design.","publisher":{"@id":"https:\/\/www.intolight.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intolight.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.intolight.de\/#organization","name":"intolight","url":"https:\/\/www.intolight.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.intolight.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/11\/1520-x-1100_0004_Dave_Kreuzkirche_2016-2.jpg","contentUrl":"https:\/\/www.intolight.de\/wp-content\/uploads\/2018\/11\/1520-x-1100_0004_Dave_Kreuzkirche_2016-2.jpg","width":1520,"height":1100,"caption":"intolight"},"image":{"@id":"https:\/\/www.intolight.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/intolight.de","https:\/\/x.com\/intolightfeed","https:\/\/de.linkedin.com\/company\/intolight","https:\/\/www.youtube.com\/channel\/UCG6VNyutvmFQ6NuEwAmZxeg"]}]}},"_links":{"self":[{"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/avada_portfolio\/14941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/comments?post=14941"}],"version-history":[{"count":0,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/avada_portfolio\/14941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/media\/14958"}],"wp:attachment":[{"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/media?parent=14941"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/portfolio_category?post=14941"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/portfolio_skills?post=14941"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/www.intolight.de\/en\/wp-json\/wp\/v2\/portfolio_tags?post=14941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}